{"id":6911,"date":"2025-12-18T15:13:27","date_gmt":"2025-12-18T15:13:27","guid":{"rendered":"https:\/\/nisrentacar.rs\/de\/?page_id=6911"},"modified":"2026-03-09T07:44:25","modified_gmt":"2026-03-09T07:44:25","slug":"fahrzeugmietbedingungen","status":"publish","type":"page","link":"https:\/\/nisrentacar.rs\/de\/fahrzeugmietbedingungen\/","title":{"rendered":"Fahrzeugmietbedingungen"},"content":{"rendered":"\n<div class=\"wp-block-uicore-container uicore-block-kjmmclgjx9\"><\/div>\n\n\n\n<section class=\"wp-block-uicore-container uicore-block-6eq2c4kz1u\"><div class=\"uicore-bl-container\">\n<h2 class=\"wp-block-uicore-heading uicore-block-hrce15gin9 uicore-bl-title uicore-bl-content\">Machen Sie sich mit den Details des Fahrzeugkreditvertrags vertraut.<\/h2>\n\n\n\n<h3 class=\"wp-block-uicore-heading uicore-block-hlhl52lfjs uicore-bl-title uicore-bl-content\">Einf\u00fchrung<\/h3>\n\n\n\n<p class=\"wp-block-uicore-paragraph uicore-block-g42zr6cemz uicore-bl-content\">Die Pkw- und Leichtkraftwagenvermietung Inex Lux Rent a car (nachfolgend &#8211; der Vermieter) vermietet das Fahrzeug an den Mieter (nachfolgend &#8211; den Nutzer) p\u00fcnktlich und zu den in diesem Vertrag festgelegten Bedingungen.<\/p>\n\n\n\n<h3 class=\"wp-block-uicore-heading uicore-block-ltimazsct7 uicore-bl-title uicore-bl-content\">Artikel 1.<\/h3>\n\n\n\n<p class=\"wp-block-uicore-paragraph uicore-block-kus8rugotg uicore-bl-content\">Der Nutzer verpflichtet sich, die folgenden Allgemeinen Gesch\u00e4ftsbedingungen zu akzeptieren und einzuhalten sowie alle Rechte und Pflichten aus diesem Vertrag zu \u00fcbernehmen:<br>Die in der g\u00fcltigen Preisliste aufgef\u00fchrten Preise und sonstigen Mietbedingungen als integralen Bestandteil dieses Vertrags zu akzeptieren;<br>Mindestalter 21 Jahre und seit mindestens zwei Jahren g\u00fcltiger F\u00fchrerschein;<br>Das Fahrzeug in einwandfreiem Zustand, vollgetankt und mit s\u00e4mtlichem Zubeh\u00f6r und allen dazugeh\u00f6rigen Dokumenten zu \u00fcbernehmen und im gleichen Zustand zur\u00fcckzugeben;<br>Das Mietfahrzeug innerhalb der auf der Vorderseite angegebenen Frist oder auf Verlangen des Vermieters auch fr\u00fcher mit einer Versp\u00e4tungstoleranz von 60 Minuten zur\u00fcckzugeben. Nach Ablauf dieser Frist wird ein zus\u00e4tzlicher Miettag berechnet;<br>Die Verl\u00e4ngerung der vereinbarten Mietdauer bedarf der Zustimmung des Vermieters 24 Stunden vor dem R\u00fcckgabetermin;<br>Bei Ausfall des Kilometerz\u00e4hlers w\u00e4hrend der Fahrt das Fahrzeug unverz\u00fcglich einzustellen und den Vermieter umgehend \u00fcber den Ausfall zu informieren;<br>Ja, falls bei der R\u00fcckgabe des Fahrzeugs ein besch\u00e4digter Kilometerz\u00e4hler festgestellt wird, ist dem Vermieter der Betrag f\u00fcr 500 gefahrene Kilometer pro Nutzungstag zu erstatten.<br>Das Fahrzeug ist w\u00e4hrend der Nutzung ordnungsgem\u00e4\u00df zu warten und zu lagern.<br>Das gemietete Fahrzeug darf nicht benutzt werden:<br>unter Alkohol- oder Drogeneinfluss;<br>f\u00fcr illegale Zwecke (z. B. Straftaten, Zoll- oder Devisenverst\u00f6\u00dfe);<br>f\u00fcr Fahrschulungen;<br>zur entgeltlichen Bef\u00f6rderung von Personen oder G\u00fctern;<br>zum Abschleppen anderer Fahrzeuge oder Anh\u00e4nger;<br>zur Teilnahme an Motorsportveranstaltungen;<br>zum Transport von Tieren, leicht entz\u00fcndlichen und explosiven Stoffen, stark riechenden Stoffen oder tankartigen Materialien, die das Fahrzeug besch\u00e4digen k\u00f6nnen;<br>w\u00e4hrend eines bestehenden Fahrverbots;<br>w\u00e4hrend des Ablaufs der Fahrerlaubnis.<br>Das Fahrzeug darf ausschlie\u00dflich f\u00fcr den pers\u00f6nlichen Gebrauch genutzt und nicht an Dritte vermietet oder verliehen werden. &#8211; Das Fahrzeug wird vom Mieter oder einer von ihm bevollm\u00e4chtigten Person gefahren, sofern diese Person mindestens 21 Jahre alt ist, seit mindestens zwei Jahren einen g\u00fcltigen F\u00fchrerschein besitzt und im Abschnitt \u201eZweiter Fahrer\u201c dieses Vertrags eingetragen ist;<br>Das Mietfahrzeug darf nicht mit mehr Personen oder Gegenst\u00e4nden als zul\u00e4ssig beladen werden;<br>Das Mietfahrzeug darf ohne Genehmigung des Vermieters nicht das Staatsgebiet von Serbien und Richardson (SRB) durchqueren;<br>Ohne die Zustimmung des Vermieters d\u00fcrfen keine \u00c4nderungen an Teilen, Baugruppen oder Vorrichtungen des Fahrzeugs vorgenommen oder dieses ver\u00e4u\u00dfert werden.<\/p>\n\n\n\n<h3 class=\"wp-block-uicore-heading uicore-block-pm8z42ewnd uicore-bl-title uicore-bl-content\">Artikel 2.<\/h3>\n\n\n\n<p class=\"wp-block-uicore-paragraph uicore-block-1ehcg54j9d uicore-bl-content\">Falls im Falle von Fahrl\u00e4ssigkeit die Reifen, Felgen und der Unterboden des Fahrzeugs, der Antriebsmechanismus des Fahrzeugs oder sonstige Sch\u00e4den am Fahrzeug des Vermieters entstehen und kein Verkehrsunfall vorlag, ist der Nutzer verpflichtet, den Vermieter unverz\u00fcglich zu benachrichtigen und ihm den gesamten Schaden in H\u00f6he der Fahrzeugreparaturkosten und des entgangenen Tagesmietbetrags gem\u00e4\u00df der aktuellen Preisliste f\u00fcr die Dauer der Fahrzeugreparatur zu erstatten.<\/p>\n\n\n\n<h3 class=\"wp-block-uicore-heading uicore-block-tj54yx49x7 uicore-bl-title uicore-bl-content\">Artikel 3.<\/h3>\n\n\n\n<p class=\"wp-block-uicore-paragraph uicore-block-aomgmbumip uicore-bl-content\">Verst\u00f6\u00dft der Nutzer gegen eine Bestimmung oder Bedingung aus Artikel 1 und Artikel 2 des Mietvertrags, so ist er verpflichtet, dem Vermieter alle daraus entstehenden Sch\u00e4den zu ersetzen; die H\u00f6he des Schadensersatzes wird vom Vermieter festgelegt.<\/p>\n\n\n\n<h3 class=\"wp-block-uicore-heading uicore-block-6vgpmmqrcb uicore-bl-title uicore-bl-content\">Artikel 4.<\/h3>\n\n\n\n<p class=\"wp-block-uicore-paragraph uicore-block-wragvljm53 uicore-bl-content\">F\u00fcr den Verlust von Dokumenten oder Schl\u00fcsseln berechnen wir eine Entsch\u00e4digung in H\u00f6he von 300,00 EUR (entsprechend dem Dinar-Gegenwert).<\/p>\n\n\n\n<h3 class=\"wp-block-uicore-heading uicore-block-zgpihr83rc uicore-bl-title uicore-bl-content\">Artikel 5.<\/h3>\n\n\n\n<p class=\"wp-block-uicore-paragraph uicore-block-9lgvd5987v uicore-bl-content\">Der Leasinggeber erstattet dem Nutzer der Dienstleistungen auf Vorlage einer Zahlungsbest\u00e4tigung die Kosten f\u00fcr die regelm\u00e4\u00dfige Wartung des Fahrzeugs (mit Ausnahme der Kosten f\u00fcr die Fahrzeugw\u00e4sche) und vorbehaltlich der zwingenden vorherigen Zustimmung des Fahrzeugleasinggebers.<\/p>\n\n\n\n<h3 class=\"wp-block-uicore-heading uicore-block-mg08tb8r0v uicore-bl-title uicore-bl-content\">Artikel 6.<\/h3>\n\n\n\n<p class=\"wp-block-uicore-paragraph uicore-block-afnhu18kj8 uicore-bl-content\">Der Nutzer verpflichtet sich, dem Vermieter auf dessen erste Aufforderung hin unverz\u00fcglich folgende Betr\u00e4ge zu zahlen:<br>Tagesmiete und Kilometergeld f\u00fcr das Mietfahrzeug sowie sonstige anfallende Kosten;<br>Nutzungsgeb\u00fchr f\u00fcr das Fahrzeug gem\u00e4\u00df der g\u00fcltigen Preisliste;<br>Bu\u00dfgelder, die dem Nutzer im Zusammenhang mit der Fahrzeugnutzung aufgrund seines Verschuldens (Versto\u00df gegen die Stra\u00dfenverkehrsordnung) auferlegt werden;<br>Gerichts- und Anwaltskosten, die dem Vermieter durch die Geltendmachung seiner Anspr\u00fcche entstehen.<\/p>\n\n\n\n<h3 class=\"wp-block-uicore-heading uicore-block-nf3r6gd79r uicore-bl-title uicore-bl-content\">Artikel 7.<\/h3>\n\n\n\n<p class=\"wp-block-uicore-paragraph uicore-block-exu2az4xzi uicore-bl-content\">Im Falle der Nichtzahlung der im Rahmen dieses Vertrags entstandenen Kosten wird der Vermieter rechtliche Schritte gegen den Nutzer der Dienstleistungen einleiten, um seine Forderungen einzutreiben und Verzugszinsen zu berechnen.<\/p>\n\n\n\n<h3 class=\"wp-block-uicore-heading uicore-block-3bzko5ar0k uicore-bl-title uicore-bl-content\">Artikel 8.<\/h3>\n\n\n\n<p class=\"wp-block-uicore-paragraph uicore-block-fn3qjmackx uicore-bl-content\">Bei Nutzung des Mietfahrzeugs ist der Nutzer gem\u00e4\u00df den geltenden gesetzlichen Bestimmungen und Versicherungsbedingungen haftpflichtversichert. Das Fahrzeug ist ebenfalls vollkaskoversichert. Der Nutzer tr\u00e4gt jedoch, auch wenn er keine Schuld am Schaden tr\u00e4gt, einen Anteil von 10 % am Schaden. Wurde der Schaden am Fahrzeug durch sein Verschulden verursacht, haftet er zus\u00e4tzlich f\u00fcr den durch die Nichtnutzung (Standzeit des besch\u00e4digten Fahrzeugs w\u00e4hrend der gesamten Reparaturdauer) entstehenden Schaden in H\u00f6he des pauschalierten Tagesmietpreises gem\u00e4\u00df der g\u00fcltigen Preisliste.<\/p>\n\n\n\n<h3 class=\"wp-block-uicore-heading uicore-block-gp8k9pe8cc uicore-bl-title uicore-bl-content\">Artikel 9.<\/h3>\n\n\n\n<p class=\"wp-block-uicore-paragraph uicore-block-eo7xodqszt uicore-bl-content\">Der Nutzer verpflichtet sich, das Fahrzeug abzuschlie\u00dfen und die Schl\u00fcssel mit sich zu f\u00fchren, wenn er das Fahrzeug nicht benutzt. Verf\u00fcgt das Fahrzeug \u00fcber eine Alarmanlage, ist der Nutzer verpflichtet, diese jedes Mal zu aktivieren, wenn er das Fahrzeug verl\u00e4sst.<\/p>\n\n\n\n<h3 class=\"wp-block-uicore-heading uicore-block-j6whgtqu4f uicore-bl-title uicore-bl-content\">Artikel 10.<\/h3>\n\n\n\n<p class=\"wp-block-uicore-paragraph uicore-block-gxc4emphwb uicore-bl-content\">Der Nutzer verpflichtet sich, den technischen Zustand des Fahrzeugs w\u00e4hrend der gesamten Mietdauer zu pflegen, regelm\u00e4\u00dfig K\u00fchlmittel, \u00d6l und Reifendruck zu pr\u00fcfen und gegebenenfalls \u00d6lwechsel nach vorheriger Zustimmung des Vermieters durchzuf\u00fchren. Der Nutzer haftet f\u00fcr alle Sch\u00e4den, die durch unsachgem\u00e4\u00dfe Wartung des Fahrzeugs entstehen, und ist zum Ersatz verpflichtet.<\/p>\n\n\n\n<h3 class=\"wp-block-uicore-heading uicore-block-7hn23bt0dp uicore-bl-title uicore-bl-content\">Artikel 11.<\/h3>\n\n\n\n<p class=\"wp-block-uicore-paragraph uicore-block-in5qz744y1 uicore-bl-content\">S\u00e4mtliche Sch\u00e4den, die Dritten durch die Angabe unrichtiger oder falscher Informationen \u00fcber sich selbst, seine Adresse oder Dokumente seitens des Nutzers des Dienstes entstehen, tr\u00e4gt ausschlie\u00dflich der Nutzer des Dienstes.<\/p>\n\n\n\n<h3 class=\"wp-block-uicore-heading uicore-block-krlucayeph uicore-bl-title uicore-bl-content\">Artikel 12.<\/h3>\n\n\n\n<p class=\"wp-block-uicore-paragraph uicore-block-9it5tbv5vu uicore-bl-content\">F\u00fcr die Dauer des Mietvertrags tr\u00e4gt der Nutzer die Kosten f\u00fcr das Parken in der Garage, etwaige Bu\u00dfgelder und sonstige unvorhergesehene Kosten. Der Vermieter ist berechtigt, dem Nutzer nachtr\u00e4glich alle weiteren Verst\u00f6\u00dfe oder Bu\u00dfgelder in Rechnung zu stellen, f\u00fcr die er als Fahrzeughalter verantwortlich ist.<\/p>\n\n\n\n<h3 class=\"wp-block-uicore-heading uicore-block-rf1yz2k1am uicore-bl-title uicore-bl-content\">Artikel 13.<\/h3>\n\n\n\n<p class=\"wp-block-uicore-paragraph uicore-block-ni12x40rh9 uicore-bl-content\">Der Nutzer des Dienstes haftet f\u00fcr alle Sch\u00e4den:<br>die an einem Fahrzeug entstehen, wenn er oder ein von ihm autorisierter Fahrer (ein anderer Fahrer) unter Alkohol- oder Drogeneinfluss steht;<br>wenn der Schaden vors\u00e4tzlich oder grob fahrl\u00e4ssig verursacht wurde;<br>wenn der Fahrer zum Zeitpunkt des Schadens keine g\u00fcltige Fahrerlaubnis besa\u00df;<br>wenn zum Zeitpunkt des Schadens ein Fahrverbot gegen den Fahrer bestand;<br>wenn er den Schaden nicht der Polizei meldet und keine Anzeige erstattet.<\/p>\n\n\n\n<h3 class=\"wp-block-uicore-heading uicore-block-6x0jq76bw6 uicore-bl-title uicore-bl-content\">Artikel 14.<\/h3>\n\n\n\n<p class=\"wp-block-uicore-paragraph uicore-block-e8dk9i2hql uicore-bl-content\">Der Vermieter leistet keinen Schadensersatz an den Mieter f\u00fcr den Verlust oder die Besch\u00e4digung von pers\u00f6nlichem Gep\u00e4ck, das sich im oder auf dem Mietfahrzeug befindet.<\/p>\n\n\n\n<h3 class=\"wp-block-uicore-heading uicore-block-mrlap89527 uicore-bl-title uicore-bl-content\">Artikel 15.<\/h3>\n\n\n\n<p class=\"wp-block-uicore-paragraph uicore-block-gz0vagi3tm uicore-bl-content\">Der Nutzer des Dienstes haftet f\u00fcr alle Sch\u00e4den am Fahrzeug, wie z. B. Sch\u00e4den, die durch fahrl\u00e4ssige Nutzung des Fahrzeugs verursacht werden, wenn er grob gegen eine allgemeine Bestimmung dieses Vertrags verst\u00f6\u00dft, zu der er sich durch die Unterzeichnung dieses Vertrags verpflichtet hat.<\/p>\n\n\n\n<h3 class=\"wp-block-uicore-heading uicore-block-mcrf8dl8f8 uicore-bl-title uicore-bl-content\">Artikel 16.<\/h3>\n\n\n\n<p class=\"wp-block-uicore-paragraph uicore-block-gc9qpj6hvr uicore-bl-content\">Der Nutzer verpflichtet sich, die Interessen des Vermieters und dessen Versicherung im Falle eines Verkehrsunfalls zu wahren, indem er:<br>die Namen und Adressen der Unfallbeteiligten und Zeugen erfasst;<br>das besch\u00e4digte Fahrzeug versichert;<br>den Vermieter unverz\u00fcglich \u00fcber den Schaden informiert, auch wenn dieser geringf\u00fcgig ist;<br>die Verkehrspolizei verst\u00e4ndigt und deren Eintreffen abwartet;<br>im Falle eines Fahrzeugbrands das PP-Ger\u00e4t benutzt.<\/p>\n\n\n\n<h3 class=\"wp-block-uicore-heading uicore-block-vs2g4vargq uicore-bl-title uicore-bl-content\">Artikel 17.<\/h3>\n\n\n\n<p class=\"wp-block-uicore-paragraph uicore-block-i1ooa8cyc1 uicore-bl-content\">Wenn der Nutzer des Dienstes im Falle eines Unfalls die oben genannten Ma\u00dfnahmen nicht ergreift, haftet er gegen\u00fcber dem Vermieter f\u00fcr alle daraus entstehenden Folgen und Sch\u00e4den.<\/p>\n\n\n\n<h3 class=\"wp-block-uicore-heading uicore-block-5ce90h85ui uicore-bl-title uicore-bl-content\">Artikel 18.<\/h3>\n\n\n\n<p class=\"wp-block-uicore-paragraph uicore-block-xjuru9yqwl uicore-bl-content\">Gibt der Nutzer das Fahrzeug nicht bis zum vereinbarten, auf der Vorderseite des Vertrags angegebenen Termin zur\u00fcck und begleicht er seine Schulden nicht, ist der Vermieter berechtigt, bei der zust\u00e4ndigen Staatsanwaltschaft eine Strafanzeige gegen den Nutzer zu erstatten und die Suche nach dem Fahrzeug dem zust\u00e4ndigen Innenministerium zu melden.<\/p>\n\n\n\n<h3 class=\"wp-block-uicore-heading uicore-block-4o9dq7m6lb uicore-bl-title uicore-bl-content\">Artikel 19.<\/h3>\n\n\n\n<p class=\"wp-block-uicore-paragraph uicore-block-gj6fpk2h27 uicore-bl-content\">Mindestnutzung der Dienstleistungen 24 Stunden.<\/p>\n\n\n\n<h3 class=\"wp-block-uicore-heading uicore-block-xltjxsfv3f uicore-bl-title uicore-bl-content\">Artikel 20.<\/h3>\n\n\n\n<p class=\"wp-block-uicore-paragraph uicore-block-zgsaat733u uicore-bl-content\">Der Reifenverschlei\u00df wird vor Fahrzeug\u00fcbernahme gemessen. \u00dcberschreitet der Reifenverschlei\u00df die festgelegte Kilometerzahl, ist der Leasingnehmer verpflichtet, die vom Leasinggeber berechneten Kosten zu tragen.<\/p>\n\n\n\n<h3 class=\"wp-block-uicore-heading uicore-block-kbz032lszb uicore-bl-title uicore-bl-content\">Artikel 21.<\/h3>\n\n\n\n<p class=\"wp-block-uicore-paragraph uicore-block-mp1yoawm64 uicore-bl-content\">Die Zahlung erfolgt im Voraus zuz\u00fcglich einer obligatorischen Anzahlung, deren H\u00f6he in der Preisliste aufgef\u00fchrt ist.<\/p>\n\n\n\n<h3 class=\"wp-block-uicore-heading uicore-block-u15gocgbqe uicore-bl-title uicore-bl-content\">Artikel 22.<\/h3>\n\n\n\n<p class=\"wp-block-uicore-paragraph uicore-block-4y28xb0h41 uicore-bl-content\">Zus\u00e4tzliche Geb\u00fchren fallen an f\u00fcr:<br>Fahrzeuglieferung oder -abholung au\u00dferhalb von Ni\u0161 und au\u00dferhalb der Gesch\u00e4ftszeiten;<br>Autow\u00e4sche stark verschmutzter Fahrzeuge;<br>Alle Sch\u00e4den im Innen- und Au\u00dfenbereich, sofern kein Unfall gemeldet wurde;<br>Verlust des Schl\u00fcssels f\u00fcr die Alarmanlage.<\/p>\n\n\n\n<h3 class=\"wp-block-uicore-heading uicore-block-tjca9zfr68 uicore-bl-title uicore-bl-content\">Artikel 23.<\/h3>\n\n\n\n<p class=\"wp-block-uicore-paragraph uicore-block-cn7fvp6fxa uicore-bl-content\">\u00c4nderungen dieses Vertrags sind nur g\u00fcltig, wenn beide Parteien zustimmen und die Vereinbarung schriftlich festgehalten wird.<\/p>\n\n\n\n<h3 class=\"wp-block-uicore-heading uicore-block-pre1ej1mmr uicore-bl-title uicore-bl-content\">Artikel 24.<\/h3>\n\n\n\n<p class=\"wp-block-uicore-paragraph uicore-block-qxoezjhd4p uicore-bl-content\">Wenn der Nutzer die Mietkosten mit einer Kreditkarte bezahlt, erm\u00e4chtigt er mit seiner Unterschrift auf dem Originalvertrag den Vermieter, die gesamten Mietkosten im Namen der Organisation, die die Kreditkarte ausgestellt hat, in Rechnung zu stellen.<\/p>\n\n\n\n<h3 class=\"wp-block-uicore-heading uicore-block-9rn495ciwu uicore-bl-title uicore-bl-content\">Artikel 25.<\/h3>\n\n\n\n<p class=\"wp-block-uicore-paragraph uicore-block-ximg65igu2 uicore-bl-content\">Der Vermieter haftet nicht f\u00fcr Sch\u00e4den, die dem Nutzer durch eine Fahrzeugpanne w\u00e4hrend der Mietzeit entstehen, sowie f\u00fcr Sch\u00e4den, die dem Nutzer durch eine versp\u00e4tete Fahrzeug\u00fcbergabe entstehen. Der Vermieter hat das Recht, das vom Nutzer gemietete Fahrzeug zu \u00fcberpr\u00fcfen.<\/p>\n\n\n\n<h3 class=\"wp-block-uicore-heading uicore-block-xr0l0t67hb uicore-bl-title uicore-bl-content\">Artikel 26.<\/h3>\n\n\n\n<p class=\"wp-block-uicore-paragraph uicore-block-8230cui4o2 uicore-bl-content\">Im Streitfall ist das Gericht in Ni\u0161 zust\u00e4ndig.<\/p>\n\n\n\n<h3 class=\"wp-block-uicore-heading uicore-block-hasq0fod08 uicore-bl-title uicore-bl-content\">Artikel 27.<\/h3>\n\n\n\n<p class=\"wp-block-uicore-paragraph uicore-block-1qtz1939no uicore-bl-content\">Der Vertrag wird in einer ausreichenden Anzahl identischer Ausfertigungen erstellt, wobei f\u00fcr jede Vertragspartei eine Ausfertigung \u201eeine\u201c Ausfertigung erhalten wird, einschlie\u00dflich Artikel 27 dieses Vertrags, und dieser Vertrag stellt den freien, ausdr\u00fccklichen Willen der Vertragsparteien dar, sodass sie ihn als solchen annehmen und unterzeichnen.<\/p>\n<\/div><\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uicore_block_fonts":"","footnotes":""},"class_list":["post-6911","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/nisrentacar.rs\/de\/wp-json\/wp\/v2\/pages\/6911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nisrentacar.rs\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nisrentacar.rs\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nisrentacar.rs\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/nisrentacar.rs\/de\/wp-json\/wp\/v2\/comments?post=6911"}],"version-history":[{"count":9,"href":"https:\/\/nisrentacar.rs\/de\/wp-json\/wp\/v2\/pages\/6911\/revisions"}],"predecessor-version":[{"id":7673,"href":"https:\/\/nisrentacar.rs\/de\/wp-json\/wp\/v2\/pages\/6911\/revisions\/7673"}],"wp:attachment":[{"href":"https:\/\/nisrentacar.rs\/de\/wp-json\/wp\/v2\/media?parent=6911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}